{"id":5738,"date":"2024-08-30T08:03:44","date_gmt":"2024-08-30T07:03:44","guid":{"rendered":"https:\/\/www.factnest.net\/es\/?p=5738"},"modified":"2024-08-30T08:03:46","modified_gmt":"2024-08-30T07:03:46","slug":"henry-cotton-la-insolita-busqueda-de-la-curacion-para-la-locura-a-traves-de-la-extraccion-de-dientes","status":"publish","type":"post","link":"https:\/\/www.factnest.net\/es\/henry-cotton-la-insolita-busqueda-de-la-curacion-para-la-locura-a-traves-de-la-extraccion-de-dientes\/","title":{"rendered":"Henry Cotton: La Ins\u00f3lita B\u00fasqueda de la &#8216;Curaci\u00f3n&#8217; para la Locura a Trav\u00e9s de la Extracci\u00f3n de Dientes"},"content":{"rendered":"\n<p><strong>Los avances cient\u00edficos, especialmente en el campo m\u00e9dico, deben mucho a los estudios y experimentos realizados por cient\u00edficos en el pasado. Estos descubrimientos y teor\u00edas, algunos obtenidos por casualidad y otros a trav\u00e9s de experimentos aparentemente extravagantes, han impulsado a la humanidad hacia adelante. Un caso extraordinario ocurri\u00f3 a principios del siglo XX en Estados Unidos, dirigido por un m\u00e9dico estadounidense llamado Henry Cotton. Durante 26 a\u00f1os, Cotton realiz\u00f3 m\u00e1s de 645 operaciones inusuales en el hospital psiqui\u00e1trico de Trenton, tratando de curar enfermedades mentales extrayendo los dientes de los pacientes. Estaba convencido de que la locura era simplemente el resultado de infecciones corporales no tratadas, lo que lo llev\u00f3 a llevar a cabo estas extra\u00f1as experiencias para validar su teor\u00eda. Sus m\u00e9todos hicieron que muchos se preguntaran qui\u00e9n era el verdadero loco: \u00bfel paciente o el m\u00e9dico?<\/strong><\/p>\n\n\n\n<p>Cuando el Dr. Henry Cotton comenz\u00f3 a administrar el hospital psiqui\u00e1trico de Trenton en Nueva Jersey, comenz\u00f3 a extraer los dientes enfermos de sus pacientes bas\u00e1ndose en sus creencias m\u00e9dicas. Sin embargo, para su gran sorpresa, esto no siempre los curaba de su locura. De hecho, sus condiciones a menudo empeoraban, ya que las operaciones les imped\u00edan hablar claramente o comer adecuadamente. En lugar de reconocer los defectos de su enfoque terap\u00e9utico, Cotton lleg\u00f3 a la conclusi\u00f3n de que la raz\u00f3n por la que sus operaciones fracasaban era porque las infecciones se hab\u00edan propagado demasiado en el cuerpo. Por lo tanto, ampli\u00f3 sus procedimientos para incluir la extracci\u00f3n de otras partes infectadas, como las am\u00edgdalas, el est\u00f3mago, la ves\u00edcula biliar, los test\u00edculos, los ovarios y el colon \u2014o al menos eso afirmaba. Cotton reportaba haber logrado tratar al 85% de sus pacientes. Naturalmente, sus colegas admiraban y adoptaban entusiastamente sus m\u00e9todos, y los padres de ni\u00f1os mentalmente inestables estaban ansiosos por reservar un lugar en su apretada agenda. Si esto no era posible, insist\u00edan en que sus m\u00e9dicos realizaran operaciones similares.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/www.factnest.net\/es\/wp-content\/uploads\/2024\/08\/image-1152.png\" alt=\"Henry Cotton: La Ins\u00f3lita B\u00fasqueda de la 'Curaci\u00f3n' para la Locura a Trav\u00e9s de la Extracci\u00f3n de Dientes\" class=\"wp-image-5740\" srcset=\"https:\/\/www.factnest.net\/es\/wp-content\/uploads\/2024\/08\/image-1152.png 600w, https:\/\/www.factnest.net\/es\/wp-content\/uploads\/2024\/08\/image-1152-300x225.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><figcaption class=\"wp-element-caption\">Henry Cotton<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Curiosamente, Henry Cotton se volvi\u00f3 famoso y reconocido por sus tratamientos de la locura en Am\u00e9rica y Europa, a pesar de la alta tasa de mortalidad entre sus pacientes. En un momento, uno de cada tres pacientes muri\u00f3 despu\u00e9s de someterse al tratamiento de Cotton. Esta alarmante tasa llev\u00f3 a muchos pacientes a reconocer los peligros de sus operaciones y a rechazar ir al quir\u00f3fano, a menudo siendo arrastrados all\u00ed contra su voluntad. Con el aumento de la tasa de mortalidad al 30%, Cotton comenz\u00f3 a reconocer el peligro inminente, pero afirmaba que esto se deb\u00eda a que la mayor\u00eda de los pacientes ya estaban en mala condici\u00f3n f\u00edsica.<\/p>\n\n\n\n<p>Afortunadamente, no todos los m\u00e9dicos estaban bajo el hechizo de las m\u00e9todos de Cotton. Algunos psiquiatras eran esc\u00e9pticos respecto a sus cirug\u00edas, y surgieron muchas alegaciones sugiriendo que maltrataba a sus pacientes. Cotton logr\u00f3 apaciguar a sus cr\u00edticos al reemplazar a su personal de enfermer\u00eda masculino, acusado de malos tratos, por enfermeras femeninas. El New York Times coment\u00f3 sobre este cambio sugiriendo que los hombres eran generalmente demasiado duros con los pacientes, y Cotton pensaba que la presencia de enfermeras ser\u00eda mucho m\u00e1s reconfortante para los pacientes.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"356\" src=\"https:\/\/www.factnest.net\/es\/wp-content\/uploads\/2024\/08\/image-1154.png\" alt=\"Henry Cotton: La Ins\u00f3lita B\u00fasqueda de la 'Curaci\u00f3n' para la Locura a Trav\u00e9s de la Extracci\u00f3n de Dientes\" class=\"wp-image-5742\" srcset=\"https:\/\/www.factnest.net\/es\/wp-content\/uploads\/2024\/08\/image-1154.png 600w, https:\/\/www.factnest.net\/es\/wp-content\/uploads\/2024\/08\/image-1154-300x178.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><figcaption class=\"wp-element-caption\">Hospital Psiqui\u00e1trico de Trenton<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Estas pr\u00e1cticas continuaron durante 26 a\u00f1os, y en 1924 se inici\u00f3 una investigaci\u00f3n apropiada sobre los m\u00e9todos m\u00e9dicos de Henry Cotton, dirigida por la Dra. Phyllis Grenaker. Ella ten\u00eda un presentimiento de que hab\u00eda algo anormal respecto al m\u00e9dico y sus procedimientos, especialmente despu\u00e9s de observar el ambiente da\u00f1ino del hospital. Grenaker encontr\u00f3 los registros del hospital desorganizados y los datos de Cotton incoherentes. Para profundizar en la investigaci\u00f3n, entrevist\u00f3 a 62 antiguos pacientes de Cotton, descubriendo historias horribles. Descubri\u00f3 que diecisiete pacientes murieron inmediatamente despu\u00e9s de las operaciones de Cotton, mientras que otros sufrieron durante varios meses antes de morir tambi\u00e9n. Estas muertes no estaban incluidas en los registros. Otros resultados mostraron que solo cinco pacientes se hab\u00edan recuperado completamente, tres m\u00e1s hab\u00edan mostrado cierta mejor\u00eda, pero sus s\u00edntomas persist\u00edan, y el resto de los pacientes no hab\u00eda mostrado mejor\u00eda.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"415\" src=\"https:\/\/www.factnest.net\/es\/wp-content\/uploads\/2024\/08\/image-1156.png\" alt=\"Henry Cotton: La Ins\u00f3lita B\u00fasqueda de la 'Curaci\u00f3n' para la Locura a Trav\u00e9s de la Extracci\u00f3n de Dientes\" class=\"wp-image-5744\" srcset=\"https:\/\/www.factnest.net\/es\/wp-content\/uploads\/2024\/08\/image-1156.png 600w, https:\/\/www.factnest.net\/es\/wp-content\/uploads\/2024\/08\/image-1156-300x208.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n\n\n<p>Estas pruebas hicieron que la Dra. Grenaker se volviera a\u00fan m\u00e1s sospechosa. Contact\u00f3 a antiguos pacientes que hab\u00edan salido del hospital, supuestamente curados o mejorados, y descubri\u00f3 que todos segu\u00edan siendo mentalmente inestables. En paralelo con la investigaci\u00f3n de la Dra. Grenaker, se form\u00f3 un comit\u00e9 en el Senado de Nueva Jersey para examinar la situaci\u00f3n en el hospital. Durante las investigaciones, Henry Cotton de repente fingi\u00f3 locura. Con el tiempo, el informe de Grenaker fue ignorado, y el Senado perdi\u00f3 inter\u00e9s en la investigaci\u00f3n. Cotton escap\u00f3 milagrosamente de toda responsabilidad, afirmando que se hab\u00eda recuperado de su propia crisis mental al extraer algunos de sus dientes infectados, y tambi\u00e9n extrajo los dientes de su esposa e hijos como medida preventiva.<\/p>\n\n\n\n<p>La demanda por los tratamientos de Henry Cotton persisti\u00f3. No solo continu\u00f3 con sus pr\u00e1cticas quir\u00fargicas en el hospital de Trenton, sino que tambi\u00e9n viaj\u00f3 por Estados Unidos y Europa para dar conferencias y abri\u00f3 su propia cl\u00ednica privada, recibiendo a pacientes adinerados desesperados por curar a sus seres queridos. En los a\u00f1os 30, se retir\u00f3 y se convirti\u00f3 en director honorario, pero eso no le impidi\u00f3 continuar con sus operaciones. Incluso desarroll\u00f3 una nueva idea m\u00e1s extrema, creyendo que era beneficioso realizar colostom\u00edas en los ni\u00f1os para prevenir la locura y evitar que se involucraran en h\u00e1bitos poco saludables como la masturbaci\u00f3n. Tambi\u00e9n critic\u00f3 a los dentistas, creyendo que su trabajo de reparaci\u00f3n de dientes era in\u00fatil en comparaci\u00f3n con la extracci\u00f3n simple de dientes.<\/p>\n\n\n\n<p>En los a\u00f1os 30, se llevaron a cabo nuevas investigaciones por parte de la administraci\u00f3n del hospital y algunos miembros de instituciones m\u00e9dicas y agencias gubernamentales en Nueva Jersey, que examinaron los registros de 645 pacientes sometidos a los procedimientos de Cotton y los compararon con 407 pacientes que no hab\u00edan recibido esas cirug\u00edas. Encontraron que la tasa de curaci\u00f3n era m\u00e1s alta entre los pacientes no tratados por Cotton. Naturalmente, el m\u00e9dico y sus partidarios lucharon vigorosamente contra las alegaciones de que sus cirug\u00edas eran perjudiciales. En medio de esta \u00faltima batalla, Cotton muri\u00f3 de un ataque al coraz\u00f3n en 1933. Los pacientes del hospital de Trenton respiraron aliviados, ya que los registros mostraron que Cotton y sus asistentes hab\u00edan extra\u00eddo m\u00e1s de 11,000 dientes y realizado 645 grandes cirug\u00edas, causando la muerte o la deformaci\u00f3n grave de cientos de personas. A pesar de esto, un obituario en el Times lament\u00f3 la p\u00e9rdida de este \u00abgran pionero\u00bb, cuyo impacto humano seguir\u00eda presente entre nosotros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los avances cient\u00edficos, especialmente en el campo m\u00e9dico, deben mucho a los estudios y experimentos&#8230;<\/p>\n","protected":false},"author":1,"featured_media":5745,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_daextam_enable_autolinks":"1","ngg_post_thumbnail":0,"footnotes":""},"categories":[51,3],"tags":[],"class_list":["post-5738","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-y-tecnologia","category-salud"],"_links":{"self":[{"href":"https:\/\/www.factnest.net\/es\/wp-json\/wp\/v2\/posts\/5738","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.factnest.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.factnest.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.factnest.net\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.factnest.net\/es\/wp-json\/wp\/v2\/comments?post=5738"}],"version-history":[{"count":1,"href":"https:\/\/www.factnest.net\/es\/wp-json\/wp\/v2\/posts\/5738\/revisions"}],"predecessor-version":[{"id":5746,"href":"https:\/\/www.factnest.net\/es\/wp-json\/wp\/v2\/posts\/5738\/revisions\/5746"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.factnest.net\/es\/wp-json\/wp\/v2\/media\/5745"}],"wp:attachment":[{"href":"https:\/\/www.factnest.net\/es\/wp-json\/wp\/v2\/media?parent=5738"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.factnest.net\/es\/wp-json\/wp\/v2\/categories?post=5738"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.factnest.net\/es\/wp-json\/wp\/v2\/tags?post=5738"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}