{"id":7046,"date":"2024-09-04T10:48:58","date_gmt":"2024-09-04T09:48:58","guid":{"rendered":"https:\/\/www.factnest.net\/fr\/?p=7046"},"modified":"2024-09-04T10:49:00","modified_gmt":"2024-09-04T09:49:00","slug":"lheritage-de-judit-polgar-la-plus-grande-joueuse-dechecs-feminine","status":"publish","type":"post","link":"https:\/\/www.factnest.net\/fr\/lheritage-de-judit-polgar-la-plus-grande-joueuse-dechecs-feminine\/","title":{"rendered":"L&rsquo;H\u00e9ritage de Judit Polgar : La Plus Grande Joueuse d&rsquo;\u00c9checs F\u00e9minine"},"content":{"rendered":"\n<p><strong>Les \u00e9checs sont souvent consid\u00e9r\u00e9s comme l&rsquo;un des plus grands jeux intellectuels, et bien que de nombreuses personnes y jouent, seules quelques-unes atteignent le titre de Grand Ma\u00eetre ou remportent des championnats internationaux. Pendant longtemps, les hommes ont domin\u00e9 le jeu, mais la joueuse hongroise Judit Polgar a chang\u00e9 cette dynamique et a mis les femmes sur la carte des \u00e9checs. Gr\u00e2ce \u00e0 son d\u00e9vouement et \u00e0 son g\u00e9nie, elle a obtenu le titre de plus grande joueuse d&rsquo;\u00e9checs de tous les temps. Son ascension peut \u00eatre attribu\u00e9e \u00e0 une personne : son p\u00e8re, Laszlo Polgar, qui a commenc\u00e9 \u00e0 entra\u00eener elle et ses s\u0153urs d\u00e8s leur jeune \u00e2ge. Il croyait que si les enfants \u00e9taient enseign\u00e9s t\u00f4t, ils pourraient devenir des g\u00e9nies dans n&rsquo;importe quel domaine.<\/strong><\/p>\n\n\n\n<p>Laszlo Polgar, enseignant de profession, a abord\u00e9 la paternit\u00e9 avec un focus acad\u00e9mique. Il a convaincu sa future \u00e9pouse, Clara, une enseignante de langue ukrainienne, de la grande mission \u00e9ducative qu&rsquo;il envisageait. Il avait l&rsquo;intention d&rsquo;\u00e9lever des prodiges et de prouver que le g\u00e9nie se cultive avec le temps et l&rsquo;entra\u00eenement, et non inn\u00e9. Clara a accept\u00e9 ses plans, et ils se sont mari\u00e9s, vivant initialement en Union Sovi\u00e9tique avant de d\u00e9m\u00e9nager dans la ville natale de Laszlo en Hongrie. Ils ont commenc\u00e9 \u00e0 planifier l&rsquo;avenir de leurs filles, Susan, Sofia et Judit Polgar. Leur strat\u00e9gie, bas\u00e9e sur des ann\u00e9es de recherche, \u00e9tait claire et directe : \u00e9duquer leurs enfants \u00e0 domicile, un choix qui a surpris les r\u00e9sidents locaux et les autorit\u00e9s de l&rsquo;\u00e9poque.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"476\" src=\"https:\/\/www.factnest.net\/fr\/wp-content\/uploads\/2024\/09\/image-543.png\" alt=\"L'H\u00e9ritage de Judit Polgar : La Plus Grande Joueuse d'\u00c9checs F\u00e9minine\" class=\"wp-image-7048\" srcset=\"https:\/\/www.factnest.net\/fr\/wp-content\/uploads\/2024\/09\/image-543.png 600w, https:\/\/www.factnest.net\/fr\/wp-content\/uploads\/2024\/09\/image-543-300x238.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><figcaption class=\"wp-element-caption\">L\u00e1szl\u00f3 Polgar avec ses filles Susan, Sofia et Judit Polgar<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Pour Laszlo, il n&rsquo;y avait pas d&rsquo;autre option. Ses recherches l&rsquo;ont convaincu que pour \u00e9lever des prodiges, il devait commencer \u00e0 les enseigner avant l&rsquo;\u00e2ge de trois ans et se sp\u00e9cialiser avant l&rsquo;\u00e2ge de six ans. Cette sp\u00e9cialisation n&rsquo;avait pas n\u00e9cessairement \u00e0 \u00eatre dans les \u00e9checs, mais pour garantir le succ\u00e8s, ses enfants devaient exceller dans n&rsquo;importe quel domaine. Clara pr\u00e9voyait de leur enseigner des langues (russe, anglais, allemand et esp\u00e9ranto) ainsi que les math\u00e9matiques avanc\u00e9es. Cependant, la s\u0153ur a\u00een\u00e9e, Susan, a choisi les \u00e9checs en raison de son amour pour les petites pi\u00e8ces du jeu. Ce choix a d\u00e9termin\u00e9 l&rsquo;avenir de ses s\u0153urs et le sien. Les parents n&rsquo;avaient aucune objection, car les \u00e9checs \u00e9taient un bon choix de sp\u00e9cialisation, \u00e9tant donn\u00e9 que le succ\u00e8s pouvait \u00eatre mesur\u00e9 pr\u00e9cis\u00e9ment par les syst\u00e8mes de classement internationaux.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"424\" src=\"https:\/\/www.factnest.net\/fr\/wp-content\/uploads\/2024\/09\/image-545.png\" alt=\"L'H\u00e9ritage de Judit Polgar : La Plus Grande Joueuse d'\u00c9checs F\u00e9minine\" class=\"wp-image-7050\" srcset=\"https:\/\/www.factnest.net\/fr\/wp-content\/uploads\/2024\/09\/image-545.png 600w, https:\/\/www.factnest.net\/fr\/wp-content\/uploads\/2024\/09\/image-545-300x212.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><figcaption class=\"wp-element-caption\">Judit Polgar avec ses s\u0153urs Susan et Sofia<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Judit Polgar, n\u00e9e en 1976, \u00e9tait la plus jeune de ses s\u0153urs. Elle savait que son enfance semblait inhabituelle et reconnaissait que beaucoup supposaient que sa vie et celle de ses s\u0153urs \u00e9taient difficiles. Cependant, pour elle, c&rsquo;\u00e9tait le contraire. Entour\u00e9e de s\u0153urs d\u00e9j\u00e0 exceptionnelles aux \u00e9checs, Judit \u00e9tait impatiente d&rsquo;apprendre. Les \u00e9checs sont devenus une activit\u00e9 familiale qui les liait dans une soci\u00e9t\u00e9 sceptique de leurs activit\u00e9s. Ils \u00e9taient fr\u00e9quemment sujets aux attaques, critiques et doutes. Beaucoup remettaient en question la capacit\u00e9 des femmes \u00e0 exceller aux \u00e9checs, consid\u00e9rant que c&rsquo;\u00e9tait un jeu mental et que les femmes n&rsquo;\u00e9taient tout simplement pas aussi intelligentes que les hommes. Son p\u00e8re, Laszlo Polgar, a r\u00e9fut\u00e9 cela, insistant sur le fait que le probl\u00e8me \u00e9tait un manque de formation ad\u00e9quate et qu&rsquo;avec suffisamment de pratique, les femmes pouvaient jouer aussi bien que les hommes, voire mieux. Cela s&rsquo;est av\u00e9r\u00e9 vrai au fil du temps.<\/p>\n\n\n\n<p>Judit Polgar pratiquait les \u00e9checs quotidiennement pendant cinq \u00e0 six heures. \u00c0 l&rsquo;\u00e2ge de cinq ans, elle avait d\u00e9j\u00e0 battu son p\u00e8re, et \u00e0 quinze ans, elle est devenue la plus jeune personne \u00e0 obtenir le titre de Grand Ma\u00eetre, le plus haut titre en \u00e9checs. Elle a domin\u00e9 les tournois r\u00e9serv\u00e9s aux femmes, mais a trouv\u00e9 la comp\u00e9tition facile. Elle a convenu avec son p\u00e8re que la plupart des autres femmes n&rsquo;\u00e9taient pas assez form\u00e9es pour d\u00e9fier les adversaires et voulait tester ses comp\u00e9tences aux plus hauts niveaux, ce qui signifiait rivaliser avec des joueurs masculins qui dominaient le monde des \u00e9checs.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"543\" src=\"https:\/\/www.factnest.net\/fr\/wp-content\/uploads\/2024\/09\/image-547.png\" alt=\"L'H\u00e9ritage de Judit Polgar : La Plus Grande Joueuse d'\u00c9checs F\u00e9minine\" class=\"wp-image-7052\" srcset=\"https:\/\/www.factnest.net\/fr\/wp-content\/uploads\/2024\/09\/image-547.png 600w, https:\/\/www.factnest.net\/fr\/wp-content\/uploads\/2024\/09\/image-547-300x272.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n\n\n<p>Bien que Judit Polgar ait voulu rivaliser avec les hommes, sa s\u0153ur Susan a bris\u00e9 cette barri\u00e8re en 1986 en devenant la premi\u00e8re femme \u00e0 se qualifier pour le championnat du monde des hommes et a rapidement obtenu le titre de Grand Ma\u00eetre. Judit a suivi ses traces, bien que leur succ\u00e8s n&rsquo;ait pas toujours \u00e9t\u00e9 bien accueilli par les joueurs masculins plus \u00e2g\u00e9s qui les battaient r\u00e9guli\u00e8rement. Susan a not\u00e9 que certains joueurs masculins n&rsquo;admettaient jamais avoir \u00e9t\u00e9 battus par une femme et trouvaient toujours des excuses pour leurs d\u00e9faites, comme des maux de t\u00eate ou des douleurs \u00e0 l&rsquo;estomac.<\/p>\n\n\n\n<p>M\u00eame lorsque Susan et Judit Polgar progressaient rapidement dans les classements mondiaux, de nombreux meilleurs joueurs du monde doutaient encore de la capacit\u00e9 des femmes \u00e0 jouer comme les hommes. Garry Kasparov, le joueur le mieux class\u00e9 au monde, a d\u00e9clar\u00e9 \u00e0 propos de Judit : \u00ab Elle est talentueuse, mais pas exceptionnellement, car les femmes ne sont pas naturellement des joueuses d&rsquo;\u00e9checs exceptionnelles. \u00bb En 1994, Kasparov a eu l&rsquo;occasion de tester les comp\u00e9tences de Judit Polgar en personne. Leur match a \u00e9t\u00e9 controvers\u00e9 lorsque Kasparov a d\u00e9plac\u00e9 son cheval, mais a ensuite reconsid\u00e9r\u00e9 le mouvement et l&rsquo;a retir\u00e9. Selon les r\u00e8gles, une fois qu&rsquo;un joueur rel\u00e2che une pi\u00e8ce, le mouvement est final. Malgr\u00e9 cela, l&rsquo;arbitre a permis \u00e0 Kasparov de revenir sur son mouvement, et il a finalement gagn\u00e9 la partie.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"337\" src=\"https:\/\/www.factnest.net\/fr\/wp-content\/uploads\/2024\/09\/image-549.png\" alt=\"L'H\u00e9ritage de Judit Polgar : La Plus Grande Joueuse d'\u00c9checs F\u00e9minine\" class=\"wp-image-7054\" srcset=\"https:\/\/www.factnest.net\/fr\/wp-content\/uploads\/2024\/09\/image-549.png 600w, https:\/\/www.factnest.net\/fr\/wp-content\/uploads\/2024\/09\/image-549-300x169.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><figcaption class=\"wp-element-caption\">Judit Polgar contre Garry Kasparov<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Malgr\u00e9 cette d\u00e9faite am\u00e8re contre Kasparov, Judit Polgar n&rsquo;a pas perdu courage. L&rsquo;ann\u00e9e suivante, elle \u00e9tait class\u00e9e dixi\u00e8me meilleure joueuse au monde et a continu\u00e9 \u00e0 jouer aux \u00e9checs professionnellement pendant quelques ann\u00e9es. En 2005, elle \u00e9tait class\u00e9e huiti\u00e8me mondialement et a rencontr\u00e9 Kasparov 17 fois pendant cette p\u00e9riode, remportant une partie et faisant quatre \u00e9galit\u00e9s. Apr\u00e8s la naissance de son enfant en 2006, elle a d\u00e9cid\u00e9 de se retirer de la comp\u00e9tition, expliquant que ses priorit\u00e9s avaient simplement chang\u00e9 pour se concentrer sur l&rsquo;\u00e9criture de livres, l&rsquo;organisation d&rsquo;\u00e9v\u00e9nements d&rsquo;\u00e9checs et l&rsquo;\u00e9ducation de sa fille. Elle a d\u00e9crit ces activit\u00e9s comme \u00e9quilibr\u00e9es et offrant une nouvelle perspective sur la vie.<\/p>\n\n\n\n<p>M\u00eame avec ces nouvelles occupations, Judit Polgar n&rsquo;a jamais perdu d&rsquo;int\u00e9r\u00eat pour les \u00e9checs. Elle a continu\u00e9 \u00e0 participer \u00e0 des tournois jusqu&rsquo;\u00e0 sa retraite en 2014. \u00c0 ce jour, le monde des \u00e9checs se souvient des contributions de Judit et de ses s\u0153urs. Bien que Judit Polgar ne soit plus la femme la mieux class\u00e9e en \u00e9checs, elle reste un exemple inspirant pour toute femme qui aime le jeu et cherche \u00e0 exceller, rivalisant avec les hommes dans les classements.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les \u00e9checs sont souvent consid\u00e9r\u00e9s comme l&rsquo;un des plus grands jeux intellectuels, et bien que&#8230;<\/p>\n","protected":false},"author":1,"featured_media":7055,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_daextam_enable_autolinks":"1","ngg_post_thumbnail":0,"footnotes":""},"categories":[15,54],"tags":[],"class_list":["post-7046","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-celebrites-du-sport","category-sports"],"_links":{"self":[{"href":"https:\/\/www.factnest.net\/fr\/wp-json\/wp\/v2\/posts\/7046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.factnest.net\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.factnest.net\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.factnest.net\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.factnest.net\/fr\/wp-json\/wp\/v2\/comments?post=7046"}],"version-history":[{"count":1,"href":"https:\/\/www.factnest.net\/fr\/wp-json\/wp\/v2\/posts\/7046\/revisions"}],"predecessor-version":[{"id":7056,"href":"https:\/\/www.factnest.net\/fr\/wp-json\/wp\/v2\/posts\/7046\/revisions\/7056"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.factnest.net\/fr\/wp-json\/wp\/v2\/media\/7055"}],"wp:attachment":[{"href":"https:\/\/www.factnest.net\/fr\/wp-json\/wp\/v2\/media?parent=7046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.factnest.net\/fr\/wp-json\/wp\/v2\/categories?post=7046"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.factnest.net\/fr\/wp-json\/wp\/v2\/tags?post=7046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}